{"id":1385,"date":"2023-05-03T00:57:56","date_gmt":"2023-05-03T04:57:56","guid":{"rendered":"https:\/\/catalystct.wpenginepowered.com\/the-hidden-side-of-motherhood\/"},"modified":"2023-05-03T00:57:56","modified_gmt":"2023-05-03T04:57:56","slug":"the-hidden-side-of-motherhood","status":"publish","type":"post","link":"https:\/\/catalystct.org\/es\/the-hidden-side-of-motherhood\/","title":{"rendered":"El lado oculto de la maternidad"},"content":{"rendered":"<p><em>Concientizar y poner fin al estigma asociado con la salud mental materna y el agotamiento. <\/em><\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/6dc585_eaf6d3ca1dfa422f85ef6369bec32aeb~mv2.jpeg\/v1\/fit\/w_1000,h_1000,al_c,q_80\/file.png\" alt=\"\" title=\"\"><\/figure>\n<p>Si bien la maternidad ciertamente trae consigo muchas alegr\u00edas, es innegable que el embarazo, el parto y el cuidado de los ni\u00f1os a menudo tienen un costo emocional para las madres y otros miembros de la familia. Con cambios hormonales y f\u00edsicos en el cuerpo, noches de insomnio, horarios abrumadores y d\u00edas sobreestimulantes, la maternidad puede ser agotadora y provocar agotamiento. El 3 de mayo es <u><a href=\"https:\/\/wmmhday.postpartum.net\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">D\u00eda de la Salud Mental Materna<\/span><\/a><\/u>y es momento de crear conciencia sobre los problemas de salud mental que enfrentan las madres, el estigma asociado con la obtenci\u00f3n de ayuda y c\u00f3mo podemos apoyar mejor a las madres y las familias que est\u00e1n luchando. <\/p>\n<p><\/p>\n<h3><strong>Trastornos del estado de \u00e1nimo y s\u00edndrome de burnout<\/strong><\/h3>\n<p><\/p>\n<p><span style=\"color: #fb0101;\"><strong>Si est\u00e1 atravesando una crisis de salud mental o tiene pensamientos de hacerse da\u00f1o a s\u00ed mismo o a otra persona, llame o env\u00ede un mensaje de texto al 988. Si usted o un ser querido est\u00e1 en peligro inmediato, llame al 911.<\/strong><\/span><\/p>\n<p><\/p>\n<p>El cuerpo de la mujer experimenta muchos cambios durante el embarazo, el parto y el per\u00edodo posparto. Los cambios f\u00edsicos, hormonales y los cambios abruptos en el estilo de vida hacen que las nuevas madres tengan un mayor riesgo de desarrollar trastornos del estado de \u00e1nimo y de ansiedad perinatales, o PMAD. Los PMAD son m\u00e1s comunes de lo que se cree; de hecho, se estima que <u><a href=\"https:\/\/wmmhday.postpartum.net\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">1 de cada 5 mujeres<\/span><\/a><\/u> experimentar\u00e1n un PMAD durante el embarazo o hasta un a\u00f1o despu\u00e9s del parto. El m\u00e1s com\u00fan <u><a href=\"https:\/\/www.mhanational.org\/maternal-mental-health\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Trastorno de salud mental materna<\/span><\/a><\/u> Son trastornos de depresi\u00f3n y ansiedad, incluidos el TOC y el trastorno de p\u00e1nico. <\/p>\n<p><\/p>\n<p>Despu\u00e9s del per\u00edodo posparto, tanto las madres que se quedan en casa como las madres que trabajan enfrentan muchos desaf\u00edos. <u><a href=\"https:\/\/www.forbes.com\/health\/family\/stay-at-home-moms-depression\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Estudios<\/span><\/a><\/u> muestran que las madres que se quedan en casa son especialmente susceptibles a los trastornos de salud mental, como la depresi\u00f3n y la ansiedad. Estar en casa todo el d\u00eda con los ni\u00f1os y sentirse aisladas de la sociedad y de otros adultos juega un papel importante en este riesgo. <\/p>\n<p><\/p>\n<p>Todas las mam\u00e1s tambi\u00e9n corren un alto riesgo de sufrir agotamiento, <u><a href=\"https:\/\/www.nytimes.com\/2022\/05\/05\/well\/family\/parental-burnout-symptoms.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">definido<\/span><\/a><\/u> como el \u201cagotamiento f\u00edsico, emocional y mental debido a las constantes exigencias del cuidado de los hijos\u201d. <u><a href=\"https:\/\/www.psychologytoday.com\/us\/blog\/striving-thriving\/202203\/how-revive-parental-burnout\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Signos de agotamiento<\/span><\/a><\/u> Los problemas incluyen problemas para mantenerse al d\u00eda con las tareas diarias, agotamiento f\u00edsico, agobio emocional y signos de desapego de sus hijos. En los \u00faltimos a\u00f1os, la pandemia de Covid aument\u00f3 el riesgo de agotamiento, ya que muchos padres se vieron obligados a hacer malabarismos con el trabajo desde casa, la educaci\u00f3n en l\u00ednea, las preocupaciones financieras y el aislamiento. Estudios recientes muestran que hasta <u><a href=\"https:\/\/www.nytimes.com\/2022\/05\/05\/well\/family\/parental-burnout-symptoms.html\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">66% de padres que trabajan<\/span><\/a><\/u> cumplir los criterios de burnout, sentir un agotamiento intenso. <\/p>\n<p><\/p>\n<h3><strong>Poner fin al estigma <\/strong><\/h3>\n<p><\/p>\n<p>Si bien los trastornos de salud mental materna parecen ser bastante comunes, la triste verdad es que muchas mujeres se sienten avergonzadas de admitir que est\u00e1n luchando. Se estima que de 1 de cada 5 mujeres que luchan con la salud mental materna, <u><a href=\"https:\/\/wmmhday.postpartum.net\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">70% ocultar\u00e1 o minimizar\u00e1 sus s\u00edntomas.<\/span><\/a><\/u>Es posible que sientan eso al admitir su lucha, o que teman ser juzgadas o consideradas como madres no aptas. La sociedad suele pintar una imagen perfecta de c\u00f3mo deber\u00edan ser la maternidad y las familias, lo que hace que las madres sientan presi\u00f3n para encajar en ese molde. <\/p>\n<p><\/p>\n<p><u><a href=\"https:\/\/www.forbes.com\/health\/family\/stay-at-home-moms-depression\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Redes sociales<\/span><\/a><\/u> El estigma social juega un papel importante en la promoci\u00f3n del autoestigma asociado con las condiciones de salud mental, haciendo que las madres sientan que est\u00e1n fracasando si no cumplen con estos est\u00e1ndares casi imposibles. Seguir y ver a otras madres con casas perfectamente limpias y sirviendo comidas cuidadosamente equilibradas y preparadas con elegancia puede aumentar la verg\u00fcenza que siente una madre si no es capaz de hacer lo mismo. Sin embargo, debemos recordar que las personas a menudo solo se centran en las partes buenas de la maternidad y las comparten mientras ocultan sus luchas. <\/p>\n<p><\/p>\n<p>Con el fin de <u><a href=\"https:\/\/npic.org\/blog\/2022\/09\/15\/maternal-mental-health-eliminating-stigma-and-creating-solutions\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">acabar con el estigma<\/span><\/a><\/u>Es importante que brindemos apoyo, reduzcamos la culpabilizaci\u00f3n y no juzguemos a nadie. Abrir la conversaci\u00f3n y escuchar las historias de lucha de otras madres y c\u00f3mo buscaron ayuda puede ayudar a que quienes est\u00e1n pasando por dificultades se sientan menos solas y menos avergonzadas. <\/p>\n<p><\/p>\n<h3><strong>Consejos para gestionar el s\u00edndrome de burnout <\/strong><\/h3>\n<figure><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/6dc585_ac688fe4dfac45a1a474e347631c4092~mv2.png\/v1\/fit\/w_1000,h_1000,al_c,q_80\/file.png\" alt=\"\" title=\"\"><\/figure>\n<p>Si est\u00e1 sintiendo los efectos del agotamiento, incluido el cansancio, el desapego de sus hijos y la sensaci\u00f3n de incompetencia, existen muchas <u><a href=\"https:\/\/www.psychologytoday.com\/us\/blog\/striving-thriving\/202203\/how-revive-parental-burnout\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Cosas que puedes hacer e incorporar<\/span><\/a><\/u> Incorp\u00f3relo a su rutina diaria para ayudar. Algo que debe tener en cuenta es que todos estos sentimientos son normales y aceptables. Cuando no pueda hacer frente a la vida diaria durante un per\u00edodo prolongado, es hora de buscar ayuda de un profesional. Recuerde que lo mejor para un ni\u00f1o es una madre SANA.<\/p>\n<ul>\n<li>\n<p><strong>Aislamiento y soledad<\/strong> <u><a href=\"https:\/\/www.nbcnews.com\/news\/us-news\/loneliness-poses-health-risks-deadly-smoking-surgeon-general-says-rcna82453\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">afectar negativamente la salud de todos<\/span><\/a><\/u> y tambi\u00e9n son factores importantes que contribuyen al s\u00edndrome premenstrual. Si bien puede ser dif\u00edcil encontrar tiempo para socializar, es una parte importante del cuidado personal. Encontrar grupos de mam\u00e1s, tomar un caf\u00e9 con una amiga o participar en un <u><a href=\"https:\/\/www.postpartum.net\/get-help\/psi-online-support-meetings\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">grupo de apoyo en l\u00ednea<\/span><\/a><\/u> Existen algunas formas de conectarse con otras personas. Tambi\u00e9n puede llamar o enviar un mensaje de texto a la l\u00ednea de ayuda internacional de apoyo posparto, disponible las 24 horas, los 7 d\u00edas de la semana, para situaciones que no sean de emergencia.<\/p>\n<ul>\n<li>\n<p>Llama al 1-800-944-4773 (4PPD)<\/p>\n<\/li>\n<li>\n<p>#1 En espa\u00f1ol o #2 Ingl\u00e9s<\/p>\n<\/li>\n<li>\n<p>Texto en ingl\u00e9s: 800-944-4773<\/p>\n<\/li>\n<li>\n<p>Texto en espa\u00f1ol: 971-203-7773<\/p>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Tambi\u00e9n puede llamar a una l\u00ednea directa de Connecticut. Encuentre los n\u00fameros en nuestra <u><a href=\"https:\/\/www.thehubct.org\/_files\/ugd\/6dc585_3cdebc71ac634bcd9e21493c109d6fb2.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Gu\u00eda de grupos de apoyo<\/span><\/a><\/u>.\n<\/p>\n<ul>\n<li>\n<p><strong>Para ayudar con el agotamiento<\/strong>, es importante reducir la sobrecarga de estimulaci\u00f3n y tomar descansos, sin importar cu\u00e1n cortos sean. Simplemente encontrar un lugar tranquilo para cerrar los ojos, escuchar m\u00fasica relajante o salir al aire libre puede ayudar a refrescar la mente y aliviar la ansiedad. Tambi\u00e9n es importante priorizar el sue\u00f1o, incluso si no ha completado su lista diaria de tareas pendientes. La crianza de los hijos a menudo viene con una lista de tareas interminable, \u00a1pero el sue\u00f1o debe ser lo primero! Por \u00faltimo, incluir a sus hijos en actividades que ayuden a calmar la mente y el cuerpo puede ser una gran t\u00e1ctica para muchas mam\u00e1s con ni\u00f1os peque\u00f1os que no pueden escaparse. Algo simple como estirarse en el piso mientras juegan puede ayudar o hacer que se unan a usted para un ejercicio de respiraci\u00f3n profunda puede ayudarla a relajarse y ense\u00f1arles habilidades de afrontamiento positivas.\n<\/p>\n<\/li>\n<li>\n<p><strong>Si te sientes separado de tus hijos<\/strong>Se recomienda centrarse en el contacto f\u00edsico, ya que el contacto humano puede ayudar a aliviar el estr\u00e9s y desempe\u00f1a un papel importante en la creaci\u00f3n de v\u00ednculos. Puede hacerlo con abrazos, tomados de la mano, acurruc\u00e1ndose con un libro o viendo la televisi\u00f3n. Tambi\u00e9n puede incluir a sus hijos en un pasatiempo que disfrute. Eso puede ayudar a recuperar el sentido de s\u00ed mismos y, al mismo tiempo, pasar tiempo de calidad con ellos.\n<\/p>\n<\/li>\n<li>\n<p><strong>Otro efecto del agotamiento es a menudo un sentimiento de incompetencia.<\/strong>, que nunca puedes hacer lo suficiente por tus hijos. Para combatir este sentimiento, intenta practicar la autocompasi\u00f3n. Recuerda que no est\u00e1s solo, que todos los padres pasan por dificultades, y conc\u00e9ntrate en lo que necesitas emocional y f\u00edsicamente. Tambi\u00e9n es importante ser psicol\u00f3gicamente flexible, que es tu capacidad de estar presente, comprometido e implementar tus valores en tu vida diaria. Y recuerda, si sientes que necesitas ayuda, \u00a1p\u00eddela! Los padres no est\u00e1n hechos para hacerlo todo solos. <\/p>\n<\/li>\n<\/ul>\n<p><\/p>\n<p><strong>Recursos para problemas de salud mental <\/strong><\/p>\n<figure><img decoding=\"async\" src=\"https:\/\/static.wixstatic.com\/media\/6dc585_df366b9053ff49ba96effaacb86b551a~mv2.jpg\/v1\/fit\/w_754,h_1000,al_c,q_80\/file.png\" alt=\"\" title=\"\"><\/figure>\n<p>Si experimenta s\u00edntomas de un problema de salud mental, es importante hablar con un profesional m\u00e9dico y buscar ayuda.\n<\/p>\n<p>Tomando un examen en l\u00ednea <u><a href=\"https:\/\/screening.mhanational.org\/screening-tools\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">examen de salud mental<\/span><\/a><\/u> Puede ser una herramienta \u00fatil para determinar si usted est\u00e1 experimentando un trastorno del estado de \u00e1nimo, pero esto no reemplaza una evaluaci\u00f3n profesional.<\/p>\n<p><\/p>\n<p>Si necesitas hablar con alguien, el <u><a href=\"https:\/\/mchb.hrsa.gov\/national-maternal-mental-health-hotline\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">L\u00ednea directa nacional de salud mental materna<\/span><\/a><\/u> Puede ser una excelente manera de recibir apoyo y recursos gratuitos, confidenciales y las 24 horas del d\u00eda, los 7 d\u00edas de la semana. Si est\u00e1 buscando formas de apoyar a su pareja o amigo, <u><a href=\"https:\/\/www.postpartum.net\/get-help\/family\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">Aqu\u00ed hay algunos consejos<\/span><\/a><\/u>.<\/p>\n<p><\/p>\n<p>Para obtener recursos adicionales, visite nuestro <u><a href=\"http:\/\/www.thehubct.org\/mhresources\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #1155cc;\">P\u00e1gina de recursos de salud mental<\/span><\/a><\/u>.<\/p>\n<p><\/p>\n<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sensibilizar y acabar con el estigma asociado a la salud mental materna y el agotamiento. Si bien la maternidad ciertamente conlleva muchos\u2026<\/p>","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1385","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Howard Buksbaum","author_link":"https:\/\/catalystct.org\/es\/author\/howardberrycreativellc-com\/"},"_links":{"self":[{"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/posts\/1385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/comments?post=1385"}],"version-history":[{"count":0,"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/posts\/1385\/revisions"}],"wp:attachment":[{"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/media?parent=1385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/categories?post=1385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catalystct.org\/es\/wp-json\/wp\/v2\/tags?post=1385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}